{"id":235,"date":"2023-05-10T16:59:08","date_gmt":"2023-05-10T08:59:08","guid":{"rendered":"https:\/\/www.grind-into-powder.com\/?p=235"},"modified":"2023-06-14T11:10:16","modified_gmt":"2023-06-14T03:10:16","slug":"thailand-a-mineral-factory-heavy-calcium-carbonate-coating-output-1t-h-particle-size-d9710%ce%bcm-2","status":"publish","type":"post","link":"https:\/\/www.grind-into-powder.com\/pt\/tailandia-uma-fabrica-mineral-pesada-revestimento-de-carbonato-de-calcio-saida-1t-h-tamanho-de-particula-d9710\u03bcm-2\/","title":{"rendered":"Tail\u00e2ndia uma f\u00e1brica de minerais, revestimento pesado de carbonato de c\u00e1lcio, produ\u00e7\u00e3o 1T\/H, tamanho de part\u00edcula D97:10\u03bcm, 2"},"content":{"rendered":"<p class=\"wp-block-paragraph\">O cliente \u00e9 uma empresa de transforma\u00e7\u00e3o de minerais n\u00e3o met\u00e1licos de renome mundial na Tail\u00e2ndia. Nos \u00faltimos anos, a procura de carbonato de c\u00e1lcio pesado no mercado aumentou. Para expandir o projeto de carbonato de c\u00e1lcio pesado modificado, quer encontrar um novo processo de revestimento. Ap\u00f3s a inspe\u00e7\u00e3o da f\u00e1brica da EPIC Powder, a empresa ficou a saber que a EPIC Powder tem uma vasta experi\u00eancia no processamento de p\u00f3 superfino de minerais n\u00e3o met\u00e1licos. Finalmente, optaram por cooperar com a EPIC Powder e adquiriram dois conjuntos de equipamentos de moinho turbo de rolos.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Materiais:<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Carbonato de c\u00e1lcio pesado<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Granularidade:<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">D97: 5-10\u03bcm<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Sa\u00edda:<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">1T\/H<\/p>","protected":false},"excerpt":{"rendered":"<p>O cliente \u00e9 uma empresa de transforma\u00e7\u00e3o de minerais n\u00e3o met\u00e1licos de renome mundial na Tail\u00e2ndia. Nos \u00faltimos anos, a procura de carbonato de c\u00e1lcio pesado no mercado aumentou. Para expandir o projeto de carbonato de c\u00e1lcio pesado modificado, quer encontrar um novo processo de revestimento. Ap\u00f3s a inspe\u00e7\u00e3o da f\u00e1brica da EPIC Powder, soube que a EPIC Powder tem uma experi\u00eancia rica em minerais n\u00e3o met\u00e1licos [...]<\/p>","protected":false},"author":1,"featured_media":773,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[50,67,68,69],"class_list":["post-235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-calcium-carbonate","tag-powder-coating-modification-machine","tag-turbo-mill","tag-roller-mill"],"_links":{"self":[{"href":"https:\/\/www.grind-into-powder.com\/pt\/wp-json\/wp\/v2\/posts\/235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.grind-into-powder.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.grind-into-powder.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.grind-into-powder.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grind-into-powder.com\/pt\/wp-json\/wp\/v2\/comments?post=235"}],"version-history":[{"count":0,"href":"https:\/\/www.grind-into-powder.com\/pt\/wp-json\/wp\/v2\/posts\/235\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grind-into-powder.com\/pt\/wp-json\/wp\/v2\/media\/773"}],"wp:attachment":[{"href":"https:\/\/www.grind-into-powder.com\/pt\/wp-json\/wp\/v2\/media?parent=235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.grind-into-powder.com\/pt\/wp-json\/wp\/v2\/categories?post=235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.grind-into-powder.com\/pt\/wp-json\/wp\/v2\/tags?post=235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}